{"id":6859,"date":"2023-08-24T09:20:51","date_gmt":"2023-08-24T09:20:51","guid":{"rendered":"https:\/\/www.brunetpublicitat.com\/?page_id=6859"},"modified":"2025-04-10T10:04:14","modified_gmt":"2025-04-10T10:04:14","slug":"branding","status":"publish","type":"page","link":"https:\/\/brunetpublicitat.com\/ca\/branding\/","title":{"rendered":"Ag\u00e8ncia de Branding"},"content":{"rendered":"<div class=\"qodef-row-grid-section-wrapper\"  ><div class=\"qodef-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1693387061748\" ><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-6525\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-6525\" >\n\t\t\t<div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t            <div class=\"qodef-label\" style=\"margin-bottom:10px\">\n                <span class=\"qodef-label-line\" ><\/span>\n                <span class=\"qodef-label-text\" >BRANDING<\/span>\n            <\/div>\n        \t\t\t<h2 class=\"qodef-st-title\" >\n\t\t\t\tServicio de Branding para Empresas\t\t\t<\/h2>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tEn Brunet Publicitat tenemos un servicio de branding dise\u00f1ado para crear y fortalecer la identidad de tu negocio, asegurando que resuene con tu p\u00fablico objetivo y se destaque en el mercado. Desde el desarrollo de una identidad corporativa coherente hasta la creaci\u00f3n de una identidad visual atractiva, trabajamos contigo para construir una marca que refleje tus valores y misi\u00f3n. Nuestro enfoque integral abarca desde el an\u00e1lisis de mercado hasta el dise\u00f1o de logotipos y la implementaci\u00f3n de estrategias de comunicaci\u00f3n efectivas. Con m\u00e1s de 25 a\u00f1os de experiencia en el sector, en Brunet Publicitat transformamos tus ideas en una identidad de marca poderosa y memorable.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t            <div class=\"qodef-label\" style=\"margin-bottom:10px\">\n                <span class=\"qodef-label-line\" ><\/span>\n                <span class=\"qodef-label-text\" >Contacte<\/span>\n            <\/div>\n        \t\t\t<h2 class=\"qodef-st-title\" >\n\t\t\t\tNecesitas un servicio de Branding\t\t\t<\/h2>\n\t\t        \t\t\t<\/div>\n<\/div>\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<iframe class=\"contact-form-frame\" src=\"https:\/\/forms.zohopublic.eu\/brunet\/form\/FORMCONTACTOWEBMKTDIGITAL\/formperma\/VOxEE502gLajPS_KnluOJcYsZnvWr7CtC5xXe1Snjqs\" frameborder=\"0\" scrolling=\"no\" aria-label=\"FORM CONTACTO WEB_MKTDIGITAL\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"qodef-row-grid-section-wrapper\"  ><div class=\"qodef-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1744276140856 vc_column-gap-10\" ><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1744276093416\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-7836\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-7836\" >\n\t\t\t<div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\">\t\t\t<div class=\"textwidget\"><\/p>\n<div style=\"display: block; min-height: 300px;\">\n<div style=\"width: 70%; margin: auto;\">\n<h3 style=\"font-size: 30px;\">Estrategia de Marca y An\u00e1lisis<\/h3>\n<ul style=\"list-style: square;\">\n<li>An\u00e1lisis de mercado y competencia<\/li>\n<li>Definici\u00f3n de prop\u00f3sito, misi\u00f3n y valores<\/li>\n<li>Perfil del cliente ideal (buyer persona)<\/li>\n<li>Posicionamiento estrat\u00e9gico y arquitectura de marca<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>\n<\/div>\n\t\t<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1744276104446\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-9683\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-9683\" >\n\t\t\t<div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\">\t\t\t<div class=\"textwidget\"><\/p>\n<div style=\"display: block; min-height: 300px;\">\n<div style=\"width: 70%; margin: auto;\">\n<h3 style=\"font-size: 30px;\">Buyer Persona y Prop\u00f3sito de Marca<\/h3>\n<ul style=\"list-style: square;\">\n<li>Perfil del cliente ideal<\/li>\n<li>Alineaci\u00f3n estrat\u00e9gica del prop\u00f3sito de marca<\/li>\n<li>Segmentaci\u00f3n y empat\u00eda de marca<\/li>\n<li>Decisiones de branding de usuario<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>\n<\/div>\n\t\t<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1744276114369\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-3947\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-3947\" >\n\t\t\t<div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\">\t\t\t<div class=\"textwidget\"><\/p>\n<div style=\"display: block; min-height: 300px;\">\n<div style=\"width: 70%; margin: auto;\">\n<h3 style=\"font-size: 30px;\">Naming e Identidad verbal<\/h3>\n<ul style=\"list-style: square;\">\n<li>Naming de marca, productos y campa\u00f1as<\/li>\n<li>Tagline o eslogan<\/li>\n<li>Tono y voz de marca<\/li>\n<li>Storytelling y mensajes clave<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>\n<\/div>\n\t\t<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"qodef-row-grid-section-wrapper\"  ><div class=\"qodef-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1744277844951 vc_column-gap-10\" ><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1744277873006\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-2814\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-2814\" >\n\t\t\t<div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\">\t\t\t<div class=\"textwidget\"><\/p>\n<div style=\"display: block; min-height: 300px;\">\n<div style=\"width: 70%; margin: auto;\">\n<h3 style=\"font-size: 30px;\">Identidad Visual y Dise\u00f1o Corporativa<\/h3>\n<ul style=\"list-style: square;\">\n<li>Dise\u00f1o de logotipo<\/li>\n<li>Sistema gr\u00e1fico y elementos visuales<\/li>\n<li>Papeler\u00eda y materiales corporativos<\/li>\n<li>Manual de marca (brand book)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>\n<\/div>\n\t\t<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1744277880795\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-4553\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-4553\" >\n\t\t\t<div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\">\t\t\t<div class=\"textwidget\"><\/p>\n<div style=\"display: block; min-height: 300px;\">\n<div style=\"width: 70%; margin: auto;\">\n<h3 style=\"font-size: 30px;\">Branding Digital y UX\/UI<\/h3>\n<ul style=\"list-style: square;\">\n<li>Dise\u00f1o web alineado con la marca<\/li>\n<li>Dise\u00f1o de interfaces digitales (UI)<\/li>\n<li>Redes Sociales y plantillas visuales<\/li>\n<li>Experiencia de usuario (UX)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>\n<\/div>\n\t\t<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1744277891204\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-3974\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-3974\" >\n\t\t\t<div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\">\t\t\t<div class=\"textwidget\"><\/p>\n<div style=\"display: block; min-height: 300px;\">\n<div style=\"width: 70%; margin: auto;\">\n<h3 style=\"font-size: 30px;\">Lanzamiento, Activaci\u00f3n y Gesti\u00f3n<\/h3>\n<ul style=\"list-style: square;\">\n<li>Estrategia de lanzamiento o rebranding<\/li>\n<li>Desarrollo de campa\u00f1as de posicionamiento<\/li>\n<li>Consultor\u00eda y activaci\u00f3n de marca<\/li>\n<li>Formaci\u00f3n interna y gesti\u00f3n continua<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>\n<\/div>\n\t\t<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"qodef-row-grid-section-wrapper\"  ><div class=\"qodef-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1693387061748\" ><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-4600\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-4600\" >\n\t\t\t<div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t            <div class=\"qodef-label\" style=\"margin-bottom:10px\">\n                <span class=\"qodef-label-line\" ><\/span>\n                <span class=\"qodef-label-text\" >BRANDING<\/span>\n            <\/div>\n        \t\t\t<h2 class=\"qodef-st-title\" >\n\t\t\t\tBeneficios del servicio de branding\t\t\t<\/h2>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tEn Brunet Publicitat te ayudamos a construir marcas que inspiran confianza y generan valor real para tu negocio.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t\t\t\t<h3 class=\"qodef-st-title\" >\n\t\t\t\tDiferenciaci\u00f3n en el mercado\t\t\t<\/h3>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tDest\u00e1cate frente a tu competencia con una identidad \u00fanica, coherente y memorable que hable directamente al coraz\u00f3n de tus clientes.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t\t\t\t<h3 class=\"qodef-st-title\" >\n\t\t\t\tCoherencia en todos los canales\t\t\t<\/h3>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tDesde tu web hasta tus redes sociales, garantizamos una presencia visual y verbal alineada, s\u00f3lida y profesional.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t\t\t\t<h3 class=\"qodef-st-title\" >\n\t\t\t\tConexi\u00f3n con tu audiencia\t\t\t<\/h3>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tCreamos marcas con prop\u00f3sito, que conectan con las emociones y necesidades de tu p\u00fablico objetivo para generar v\u00ednculos duraderos.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t\t\t\t<h3 class=\"qodef-st-title\" >\n\t\t\t\tClaridad en tu propuesta de valor\t\t\t<\/h3>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tTe ayudamos a comunicar con claridad qui\u00e9n eres, qu\u00e9 haces y por qu\u00e9 deber\u00edan elegirte, generando confianza desde el primer contacto.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t\t\t\t<h3 class=\"qodef-st-title\" >\n\t\t\t\tImpacto visual y narrativo\t\t\t<\/h3>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tDise\u00f1amos una identidad visual potente y un discurso de marca que habla con autenticidad, coherencia y estilo propio.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t\t\t\t<h3 class=\"qodef-st-title\" >\n\t\t\t\tValor a largo plazo\t\t\t<\/h3>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tUna marca bien construida es un activo que se revaloriza con el tiempo. No solo atrae clientes, sino que fideliza y potencia el crecimiento sostenible.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-3707\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-3707\" >\n\t\t\t<div class=\"vc_empty_space\"   style=\"height: 50px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" width=\"800\" height=\"724\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/logo-be-creative-inspiration-design-concept.jpg\" class=\"vc_single_image-img attachment-large\" alt=\"agencia de branding\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/logo-be-creative-inspiration-design-concept.jpg 800w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/logo-be-creative-inspiration-design-concept-300x272.jpg 300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/logo-be-creative-inspiration-design-concept-768x695.jpg 768w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/logo-be-creative-inspiration-design-concept-13x12.jpg 13w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"qodef-row-grid-section-wrapper\"  ><div class=\"qodef-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1693387061748\" ><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-2796\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-2796\" >\n\t\t\t<div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/creative-multiracial-design-professionals-discussing-charts-office.jpg\" class=\"vc_single_image-img attachment-large\" alt=\"servicio de branding\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/creative-multiracial-design-professionals-discussing-charts-office.jpg 800w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/creative-multiracial-design-professionals-discussing-charts-office-300x200.jpg 300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/creative-multiracial-design-professionals-discussing-charts-office-768x512.jpg 768w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2025\/04\/creative-multiracial-design-professionals-discussing-charts-office-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qodef-elements-holder   qodef-one-column  qodef-responsive-mode-768\" ><div class=\"qodef-eh-item\"  data-item-class=\"qodef-eh-custom-6448\">\n\t<div class=\"qodef-eh-item-inner\">\n\t\t<div class=\"qodef-eh-item-content qodef-eh-custom-6448\" >\n\t\t\t<div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t            <div class=\"qodef-label\" style=\"margin-bottom:10px\">\n                <span class=\"qodef-label-line\" ><\/span>\n                <span class=\"qodef-label-text\" >BRANDING<\/span>\n            <\/div>\n        \t\t\t<h2 class=\"qodef-st-title\" >\n\t\t\t\tServicio ideal para empresas\t\t\t<\/h2>\n\t\t        \t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 36px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t\t\t\t<h3 class=\"qodef-st-title\" >\n\t\t\t\tStartups con visi\u00f3n\t\t\t<\/h3>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\t\u00bfEst\u00e1s lanzando una nueva marca al mercado? Te ayudamos a construir una identidad desde cero, con todos los elementos estrat\u00e9gicos y visuales necesarios para arrancar con paso firme y diferenciarte desde el primer d\u00eda.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"qodef-section-title-holder negocio qodef-st-standard qodef-st-title-left qodef-st-normal-space\" >\n\t<div class=\"qodef-st-inner\">\n\t\t\t\t\t<h3 class=\"qodef-st-title\" >\n\t\t\t\tPYMEs que quieren dar un salto\t\t\t<\/h3>\n\t\t        \t\t\t\t\t<p class=\"qodef-st-text\" style=\"margin-top: 20px\">\n\t\t\t\t\u00bfTu marca actual ya no representa lo que eres o hacia d\u00f3nde vas? Te guiamos en procesos de rebranding para renovar tu imagen, reforzar tu posicionamiento y seguir creciendo con una identidad s\u00f3lida y bien pensada.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"qodef-row-grid-section-wrapper\"  ><div class=\"qodef-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-15 vc_row-o-equal-height vc_row-flex\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1690808269824\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1690808296101\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center; text-transform: uppercase; font-size: 32px;\">ELS NOSTRES PROJECTES<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"qodef-portfolio-slider-holder\"><div class=\"qodef-portfolio-list-holder qodef-grid-list qodef-disable-bottom-space qodef-pl-gallery qodef-three-columns qodef-huge-space qodef-pl-standard-shader    qodef-pl-pag-no-pagination     qodef-pag-below-slider\"  data-type=\"gallery\" data-number-of-columns=\"three\" data-space-between-items=\"huge\" data-number-of-items=\"9\" data-image-proportions=\"square\" data-enable-fixed-proportions=\"no\" data-enable-image-shadow=\"no\" data-orderby=\"date\" data-order=\"ASC\" data-item-style=\"standard-shader\" data-enable-title=\"yes\" data-title-tag=\"h4\" data-enable-category=\"yes\" data-enable-count-images=\"yes\" data-enable-excerpt=\"no\" data-excerpt-length=\"20\" data-pagination-type=\"no-pagination\" data-filter=\"no\" data-filter-order-by=\"name\" data-enable-article-animation=\"no\" data-portfolio-slider-on=\"yes\" data-enable-loop=\"no\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\" data-pagination-position=\"below-slider\" data-max-num-pages=\"1\" data-next-page=\"2\">\n\t\t<div class=\"qodef-pl-inner qodef-outer-space qodef-owl-slider qodef-list-is-slider clearfix\">\n\t\t<article class=\"qodef-pl-item qodef-item-space  post-2072 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-autobuses portfolio-category-exterior portfolio-category-marketing-offline portfolio-tag-exterior\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/ImatgesPortfoli_1-6-650x650.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"Autobus Vimusa\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/ImatgesPortfoli_1-6-650x650.jpg 650w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/ImatgesPortfoli_1-6-150x150.jpg 150w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tProjecte Vimusa\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/autobuses\/\">Autobusos<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/exterior\/\">Exterior<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/marketing-offline\/\">M\u00e0rqueting Offline<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/vimusa\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-2265 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-exterior portfolio-category-marketing-offline portfolio-tag-exterior\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/ImatgesPortfoli_1-3-650x650.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"Brunet\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/ImatgesPortfoli_1-3-650x650.jpg 650w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/ImatgesPortfoli_1-3-150x150.jpg 150w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tTanques exteriors de Brunet\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/exterior\/\">Exterior<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/marketing-offline\/\">M\u00e0rqueting Offline<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/brunet-2\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-2266 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-exterior portfolio-category-marketing-offline portfolio-tag-exterior\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/senior-via-sabadell-650x650.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"via sabadell\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/senior-via-sabadell-650x650.jpg 650w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/senior-via-sabadell-150x150.jpg 150w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tVia Sabadell\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/exterior\/\">Exterior<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/marketing-offline\/\">M\u00e0rqueting Offline<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/via-sabadell\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-2268 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-digital portfolio-category-social-media portfolio-tag-digital\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/1-2.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"Cl\u00ednica Dental TresD\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/1-2.jpg 450w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/1-2-300x300.jpg 300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/1-2-150x150.jpg 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tCl\u00ednica Dental Tres D\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/digital\/\">Digital<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/social-media\/\">Social Media<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/dental-tresd\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1205 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-digital portfolio-category-social-media portfolio-tag-digital\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/FrutasPerez_1-650x650.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"Frutas Perez\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/FrutasPerez_1-650x650.jpg 650w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/FrutasPerez_1-150x150.jpg 150w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/FrutasPerez_1-1300x1300.jpg 1300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/FrutasPerez_1-300x300.jpg 300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/FrutasPerez_1-100x100.jpg 100w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tFrutas P\u00e9rez\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/digital\/\">Digital<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/social-media\/\">Social Media<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/frutas-perez\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-2270 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-branding portfolio-tag-branding\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/3-1.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"Pino automative\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/3-1.jpg 450w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/3-1-300x300.jpg 300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/3-1-150x150.jpg 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tProjecte Pino Automotive\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/branding\/\">Branding<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/pino\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-2267 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-digital portfolio-category-social-media portfolio-tag-digital\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/1-1.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"CPS Redes sociales\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/1-1.jpg 450w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/1-1-300x300.jpg 300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/1-1-150x150.jpg 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tClub P\u00e0del Sabadell\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/digital\/\">Digital<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/social-media\/\">Social Media<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/club-padel-sabadell\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-2269 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-branding portfolio-tag-branding\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/3-2.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"Projecte\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/3-2.jpg 450w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/3-2-300x300.jpg 300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/3-2-150x150.jpg 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tProjecta Solucions i arquitectura\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/branding\/\">Branding<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/projecta\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-2271 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-branding portfolio-tag-branding\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/2.jpg\" class=\"attachment-brunn_select_image_square size-brunn_select_image_square wp-post-image\" alt=\"Tarjetas Brunet\" srcset=\"https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/2.jpg 450w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/2-300x300.jpg 300w, https:\/\/brunetpublicitat.com\/wp-content\/uploads\/2018\/09\/2-150x150.jpg 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tBrunet Restyling\t<\/h4>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-category\/branding\/\">Branding<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/brunetpublicitat.com\/ca\/portfolio-item\/brunet-restyling\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"1. Introducci\u00f3n El objetivo de este proyecto es revitalizar la identidad visual de Brunet Publicitat a trav\u00e9s de un restyling [...]","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-6859","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/brunetpublicitat.com\/ca\/wp-json\/wp\/v2\/pages\/6859"}],"collection":[{"href":"https:\/\/brunetpublicitat.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brunetpublicitat.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brunetpublicitat.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/brunetpublicitat.com\/ca\/wp-json\/wp\/v2\/comments?post=6859"}],"version-history":[{"count":0,"href":"https:\/\/brunetpublicitat.com\/ca\/wp-json\/wp\/v2\/pages\/6859\/revisions"}],"wp:attachment":[{"href":"https:\/\/brunetpublicitat.com\/ca\/wp-json\/wp\/v2\/media?parent=6859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}